{"id":90,"date":"2023-07-16T17:28:22","date_gmt":"2023-07-16T15:28:22","guid":{"rendered":"http:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier.jpg"},"modified":"2023-07-16T17:28:22","modified_gmt":"2023-07-16T15:28:22","slug":"23_02196_22-copier","status":"inherit","type":"attachment","link":"https:\/\/carnetsdevoyage.net\/utah2023\/23_02196_22-copier\/","title":{"rendered":"23_02196_22 (Copier)"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-90","attachment","type-attachment","status-inherit","hentry"],"filename":"23_02196_22-Copier.jpg","filesize":872493,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"507\" height=\"900\" src=\"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-507x900.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-507x900.jpg 507w, https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-768x1364.jpg 768w, https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-865x1536.jpg 865w, https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-152x270.jpg 152w, https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier.jpg 901w\" sizes=\"auto, (max-width: 507px) 100vw, 507px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":901,"height":1600,"file":"2023\/07\/23_02196_22-Copier.jpg","filesize":872493,"sizes":{"medium":{"file":"23_02196_22-Copier-507x900.jpg","width":507,"height":900,"filesize":209585,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-507x900.jpg"},"thumbnail":{"file":"23_02196_22-Copier-150x150.jpg","width":150,"height":150,"filesize":52172,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-150x150.jpg"},"medium_large":{"file":"23_02196_22-Copier-768x1364.jpg","width":768,"height":1364,"filesize":406610,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-768x1364.jpg"},"1536x1536":{"file":"23_02196_22-Copier-865x1536.jpg","width":865,"height":1536,"filesize":493239,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-865x1536.jpg"},"post-thumbnail":{"file":"23_02196_22-Copier-152x270.jpg","width":152,"height":270,"filesize":58668,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-152x270.jpg"},"nisarg-full-width":{"file":"23_02196_22-Copier-901x576.jpg","width":901,"height":576,"filesize":238122,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier-901x576.jpg"},"full":{"file":"23_02196_22-Copier.jpg","width":901,"height":1600,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"DSC-RX10M3","caption":"","created_timestamp":"1689416481","copyright":"","focal_length":"18.9","iso":"100","shutter_speed":"0.004","title":"","orientation":"1","keywords":[],"lens":""}},"post":null,"source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02196_22-Copier.jpg","_links":{"self":[{"href":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-json\/wp\/v2\/media\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-json\/wp\/v2\/comments?post=90"}]}}