{"id":93,"date":"2023-07-16T17:28:33","date_gmt":"2023-07-16T15:28:33","guid":{"rendered":"http:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier.jpg"},"modified":"2023-07-16T17:28:33","modified_gmt":"2023-07-16T15:28:33","slug":"23_02208_25-copier","status":"inherit","type":"attachment","link":"https:\/\/carnetsdevoyage.net\/utah2023\/23_02208_25-copier\/","title":{"rendered":"23_02208_25 (Copier)"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-93","attachment","type-attachment","status-inherit","hentry"],"filename":"23_02208_25-Copier.jpg","filesize":787035,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"507\" src=\"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-900x507.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-900x507.jpg 900w, https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-768x432.jpg 768w, https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-1536x865.jpg 1536w, https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-479x270.jpg 479w, https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier.jpg 1600w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":901,"file":"2023\/07\/23_02208_25-Copier.jpg","filesize":787035,"sizes":{"medium":{"file":"23_02208_25-Copier-900x507.jpg","width":900,"height":507,"filesize":181775,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-900x507.jpg"},"thumbnail":{"file":"23_02208_25-Copier-150x150.jpg","width":150,"height":150,"filesize":51083,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-150x150.jpg"},"medium_large":{"file":"23_02208_25-Copier-768x432.jpg","width":768,"height":432,"filesize":143117,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-768x432.jpg"},"1536x1536":{"file":"23_02208_25-Copier-1536x865.jpg","width":1536,"height":865,"filesize":431177,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-1536x865.jpg"},"post-thumbnail":{"file":"23_02208_25-Copier-479x270.jpg","width":479,"height":270,"filesize":83338,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-479x270.jpg"},"nisarg-full-width":{"file":"23_02208_25-Copier-1038x576.jpg","width":1038,"height":576,"filesize":221993,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier-1038x576.jpg"},"full":{"file":"23_02208_25-Copier.jpg","width":1600,"height":901,"mime_type":"image\/jpeg","source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"DSC-RX10M3","caption":"","created_timestamp":"1689416886","copyright":"","focal_length":"10.6","iso":"100","shutter_speed":"0.0015625","title":"","orientation":"1","keywords":[],"lens":""}},"post":null,"source_url":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-content\/uploads\/sites\/21\/2023\/07\/23_02208_25-Copier.jpg","_links":{"self":[{"href":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-json\/wp\/v2\/media\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/carnetsdevoyage.net\/utah2023\/wp-json\/wp\/v2\/comments?post=93"}]}}